{"id":2542,"date":"2025-01-09T09:35:15","date_gmt":"2025-01-09T09:35:15","guid":{"rendered":"https:\/\/arquitecturamediterrania.com\/politique-de-cookies\/"},"modified":"2025-01-30T09:44:53","modified_gmt":"2025-01-30T09:44:53","slug":"politique-de-cookies","status":"publish","type":"page","link":"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/","title":{"rendered":"Politique de cookies"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2542\" class=\"elementor elementor-2542 elementor-2498\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28ce0f9 animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"28ce0f9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:0.5}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e337428 e-con-full e-flex e-con e-child\" data-id=\"e337428\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-190077a elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"190077a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Politique de cookies<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d9dfa0 animated-slow e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"1d9dfa0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:0.5}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c2d8faa e-con-full e-flex e-con e-child\" data-id=\"c2d8faa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63fcddd elementor-widget elementor-widget-text-editor\" data-id=\"63fcddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>BERNAT BOU OLIVER, conform\u00e9ment \u00e0 l&rsquo;article 22.2 de la Loi 34\/2002, du 11 juillet, sur les Services de la Soci\u00e9t\u00e9 de l&rsquo;Information et le Commerce \u00c9lectronique (LSSI-CE), respecte ses obligations d&rsquo;information sur les cookies utilis\u00e9s et leurs finalit\u00e9s.<\/p>\n<\/p>\n<h3>D\u00e9finition et fonction g\u00e9n\u00e9rale des cookies<\/h3>\n<p>Les cookies sont des fichiers cr\u00e9\u00e9s par un site web qui contiennent de petites quantit\u00e9s de donn\u00e9es \u00e9chang\u00e9es entre un \u00e9metteur et un r\u00e9cepteur. Ils permettent \u00e0 un site web, entre autres, de stocker et de r\u00e9cup\u00e9rer des informations sur les habitudes de navigation d&rsquo;un utilisateur ou d&rsquo;un appareil et, selon les informations qu&rsquo;ils contiennent, de reconna\u00eetre l&rsquo;utilisateur.<\/p>\n<p>Les cookies sont essentiels au fonctionnement d&rsquo;internet, offrant de nombreux avantages pour fournir des services interactifs, faciliter la navigation et am\u00e9liorer l&rsquo;utilisation des sites web.<\/p>\n<\/p>\n<h3>Types de cookies utilis\u00e9s et leurs finalit\u00e9s<\/h3>\n<p>Ce site web utilise les cookies suivants.<\/p>\n<p><u>Cookies techniques<\/u>: Ils permettent \u00e0 l&rsquo;utilisateur de naviguer sur un site web et d&rsquo;utiliser diff\u00e9rentes fonctionnalit\u00e9s (acc\u00e8s s\u00e9curis\u00e9, achats en ligne, s\u00e9curit\u00e9, contenu multim\u00e9dia, r\u00e9seaux sociaux, etc.).<\/p>\n<p><u><br \/>Cookies analytiques : <\/u>G\u00e9r\u00e9s par nous ou par des tiers, ils nous permettent de mesurer et d&rsquo;analyser statistiquement l&rsquo;utilisation des services.<\/p>\n<p><u><br \/>Cookies publicitaires : <\/u>Utilis\u00e9s pour rendre la publicit\u00e9 plus pertinente pour les utilisateurs, \u00e9viter les annonces r\u00e9p\u00e9t\u00e9es et am\u00e9liorer la performance des campagnes publicitaires. Les cookies sont g\u00e9n\u00e9ralement utilis\u00e9es pour s\u00e9lectionner des annonces bas\u00e9es sur du contenu pertinent pour un utilisateur, am\u00e9liorer les rapports de performance de la campagne et \u00e9viter d&rsquo;afficher des annonces que l&rsquo;utilisateur a d\u00e9j\u00e0 vues.<\/p>\n<p><u><br \/>Cookies de personnalisation : <\/u>Ils permettent de m\u00e9moriser des informations pour fournir une exp\u00e9rience utilisateur adapt\u00e9e (langue, r\u00e9gion, pr\u00e9f\u00e9rences de recherche, etc.).<\/p>\n<\/p>\n<h3>Acceptation volontaire des cookies et r\u00e9vocation du consentement<\/h3>\n<p>Pour utiliser ce site web, il n&rsquo;est pas n\u00e9cessaire d&rsquo;installer des cookies d&rsquo;analyse ou publicitaires. L&rsquo;installation de cookies de personnalisation n&rsquo;est \u00e9galement pas n\u00e9cessaire, sauf si ces cookies sont activ\u00e9s parce que vous avez vous-m\u00eame personnalis\u00e9 le contenu du site via une action, comme s\u00e9lectionner la langue du site en cliquant sur l&rsquo;ic\u00f4ne du drapeau correspondant. Vous pouvez accepter tous les cookies, les refuser ou personnaliser les cookies que vous acceptez et ceux que vous rejetez selon leurs finalit\u00e9s, via le bouton de configuration des cookies situ\u00e9 en bas de notre site web, \u00e0 tout moment.  Les cookies techniques ne peuvent pas \u00eatre rejet\u00e9s, car cela emp\u00eacherait le bon fonctionnement du site. Les cookies de personnalisation ne peuvent pas non plus \u00eatre rejet\u00e9s si vous avez personnalis\u00e9 les caract\u00e9ristiques avec lesquelles le site vous est affich\u00e9, par exemple en s\u00e9lectionnant une langue de navigation.<\/p>\n<p>De plus, vous pouvez configurer votre navigateur pour accepter, refuser ou vous notifier lorsqu&rsquo;un cookie sera enregistr\u00e9 sur votre ordinateur.<\/p>\n<p>Chaque navigateur est diff\u00e9rent :<\/p>\n<p>Firefox: <a href=\"http:\/\/support.mozilla.org\/fr\/kb\/activer-desactiver-cookies-preferences-sites\">http:\/\/support.mozilla.org\/fr\/kb\/activer-desactiver-cookies-preferences-sites<\/a><\/p>\n<p>Chrome : <a href=\"http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=fr&amp;answer=95647\">http:\/\/support.google.com\/chrome\/bin\/answer.py?hl=fr&amp;answer=95647<\/a><\/p>\n<p>Explorer : <a href=\"http:\/\/windows.microsoft.com\/fr-fr\/internet-explorer\/delete-manage-cookies#ie=ie-10\">http:\/\/windows.microsoft.com\/fr-fr\/internet-explorer\/delete-manage-cookies#ie=ie-10<\/a><\/p>\n<p>Safari: <a href=\"https:\/\/support.apple.com\/fr-fr\/guide\/safari\/sfri11471\/mac\">https:\/\/support.apple.com\/fr-fr\/guide\/safari\/sfri11471\/mac<\/a><\/p>\n<p><strong> <\/strong><\/p>\n<h3>Informations d\u00e9taill\u00e9es sur les cookies utilis\u00e9s sur ce site web<\/h3>\n<p>BERNAT BOU OLIVER vous informe que ce site web utilise Google Analytics, un service d\u2019analyse web fourni par Google, qui place une s\u00e9rie de cookies sur votre appareil dans le seul but d\u2019\u00e9valuer le type de navigation et de g\u00e9n\u00e9rer des rapports d\u2019activit\u00e9 sur le site web. La collecte d\u2019informations sur l\u2019utilisation de ce site web par nos utilisateurs via Google Analytics est effectu\u00e9e exclusivement par Google en son propre nom (et non au nom ni pour le compte de BERNAT BOU OLIVER). BERNAT BOU OLIVER n\u2019a \u00e0 aucun moment acc\u00e8s \u00e0 ces informations (seulement aux informations agr\u00e9g\u00e9es fournies ult\u00e9rieurement par Google et qui ne sont associ\u00e9es \u00e0 aucune adresse IP). De m\u00eame, c\u2019est Google qui d\u00e9termine la finalit\u00e9 du traitement et de l\u2019utilisation des informations collect\u00e9es, ainsi que le fonctionnement et la dur\u00e9e des cookies.<\/p>\n<p>BERNAT BOU OLIVER vous informe que le site web utilise des cookies de Google lorsqu\u2019il utilise le service Google Tag Manager pour ajouter des balises, le service d\u2019analyse web Google Analytics, ainsi que le service et la plateforme publicitaire de Google, Google Ads. Certains de ces cookies, en plus de permettre ces services sur notre site web, sont utilis\u00e9s par Google pour garantir la s\u00e9curit\u00e9 des utilisateurs contre les attaques de tiers, ainsi que pour \u00e9tablir des profils d\u2019utilisateurs bas\u00e9s sur leurs habitudes de navigation et les informations fournies afin de leur envoyer des contenus publicitaires personnalis\u00e9s et d\u2019am\u00e9liorer les services propos\u00e9s. Google ne fournit pas d\u2019informations sp\u00e9cifiques sur certains cookies ; ainsi, pour garantir votre confidentialit\u00e9, nous avons class\u00e9 tous ces cookies comme publicitaires, car ce sont les plus intrusifs pour la vie priv\u00e9e des utilisateurs. La collecte d\u2019informations sur l\u2019utilisation de ce site web par nos utilisateurs via Google est effectu\u00e9e exclusivement par Google en son propre nom (et non au nom ni pour le compte de BERNAT BOU OLIVER). BERNAT BOU OLIVER n\u2019a \u00e0 aucun moment acc\u00e8s \u00e0 ces informations.     De m\u00eame, c\u2019est Google qui d\u00e9termine la finalit\u00e9 du traitement et de l\u2019utilisation des informations collect\u00e9es, ainsi que le fonctionnement et la dur\u00e9e des cookies.<\/p>\n<p>BERNAT BOU OLIVER vous informe que le site web utilise des cookies de Meta, appartenant \u00e0 Meta Platforms, Inc., lorsqu\u2019il affiche le bouton de lien vers le r\u00e9seau social Facebook sur notre site web. Ces cookies de Meta, en plus de permettre l\u2019utilisation de ces services de Meta Platforms, Inc., sont \u00e9galement utilis\u00e9s par Meta Platforms, Inc. pour \u00e9tablir des profils d\u2019utilisateurs bas\u00e9s sur leurs habitudes de navigation afin de leur envoyer des contenus publicitaires personnalis\u00e9s et de r\u00e9aliser des analyses statistiques de leur navigation pour am\u00e9liorer les services propos\u00e9s. <\/p>\n<p>De plus, Meta Platforms, Inc. utilise des cookies pour garantir la s\u00e9curit\u00e9 des utilisateurs de ses services et pour personnaliser ses outils en fonction des pr\u00e9f\u00e9rences des utilisateurs. La collecte d\u2019informations sur l\u2019utilisation de ce site web par nos utilisateurs via Meta est effectu\u00e9e exclusivement par Meta Platforms, Inc. en son propre nom (et non au nom ni pour le compte de BERNAT BOU OLIVER). BERNAT BOU OLIVER n\u2019a \u00e0 aucun moment acc\u00e8s \u00e0 ces informations (seulement aux informations agr\u00e9g\u00e9es fournies ult\u00e9rieurement par Meta et qui ne sont associ\u00e9es \u00e0 aucune adresse IP). <\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Politique de cookies BERNAT BOU OLIVER, conform\u00e9ment \u00e0 l&rsquo;article 22.2 de la Loi 34\/2002, du 11 juillet, sur les Services de la Soci\u00e9t\u00e9 de l&rsquo;Information et le Commerce \u00c9lectronique (LSSI-CE), respecte ses obligations d&rsquo;information sur les cookies utilis\u00e9s et leurs finalit\u00e9s. D\u00e9finition et fonction g\u00e9n\u00e9rale des cookies Les cookies sont des fichiers cr\u00e9\u00e9s par un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2542","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de cookies - Arquitectura Mediterr\u00e0nia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de cookies - Arquitectura Mediterr\u00e0nia\" \/>\n<meta property=\"og:description\" content=\"Politique de cookies BERNAT BOU OLIVER, conform\u00e9ment \u00e0 l&rsquo;article 22.2 de la Loi 34\/2002, du 11 juillet, sur les Services de la Soci\u00e9t\u00e9 de l&rsquo;Information et le Commerce \u00c9lectronique (LSSI-CE), respecte ses obligations d&rsquo;information sur les cookies utilis\u00e9s et leurs finalit\u00e9s. D\u00e9finition et fonction g\u00e9n\u00e9rale des cookies Les cookies sont des fichiers cr\u00e9\u00e9s par un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Arquitectura Mediterr\u00e0nia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-30T09:44:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/fr\\\/politique-de-cookies\\\/\",\"url\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/fr\\\/politique-de-cookies\\\/\",\"name\":\"Politique de cookies - Arquitectura Mediterr\u00e0nia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/#website\"},\"datePublished\":\"2025-01-09T09:35:15+00:00\",\"dateModified\":\"2025-01-30T09:44:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/fr\\\/politique-de-cookies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/arquitecturamediterrania.com\\\/fr\\\/politique-de-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/fr\\\/politique-de-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/#website\",\"url\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/\",\"name\":\"Arquitectura Mediterr\u00e0nia\",\"description\":\"Nous construisons des espaces m\u00e9diterran\u00e9ens, sains et durables\",\"publisher\":{\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/#organization\",\"name\":\"Arquitectura Mediterr\u00e0nia\",\"url\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logotip-am.svg\",\"contentUrl\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/logotip-am.svg\",\"width\":499,\"height\":215,\"caption\":\"Arquitectura Mediterr\u00e0nia\"},\"image\":{\"@id\":\"https:\\\/\\\/arquitecturamediterrania.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de cookies - Arquitectura Mediterr\u00e0nia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/","og_locale":"fr_FR","og_type":"article","og_title":"Politique de cookies - Arquitectura Mediterr\u00e0nia","og_description":"Politique de cookies BERNAT BOU OLIVER, conform\u00e9ment \u00e0 l&rsquo;article 22.2 de la Loi 34\/2002, du 11 juillet, sur les Services de la Soci\u00e9t\u00e9 de l&rsquo;Information et le Commerce \u00c9lectronique (LSSI-CE), respecte ses obligations d&rsquo;information sur les cookies utilis\u00e9s et leurs finalit\u00e9s. D\u00e9finition et fonction g\u00e9n\u00e9rale des cookies Les cookies sont des fichiers cr\u00e9\u00e9s par un [&hellip;]","og_url":"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/","og_site_name":"Arquitectura Mediterr\u00e0nia","article_modified_time":"2025-01-30T09:44:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/","url":"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/","name":"Politique de cookies - Arquitectura Mediterr\u00e0nia","isPartOf":{"@id":"https:\/\/arquitecturamediterrania.com\/#website"},"datePublished":"2025-01-09T09:35:15+00:00","dateModified":"2025-01-30T09:44:53+00:00","breadcrumb":{"@id":"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/arquitecturamediterrania.com\/fr\/politique-de-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/arquitecturamediterrania.com\/"},{"@type":"ListItem","position":2,"name":"Politique de cookies"}]},{"@type":"WebSite","@id":"https:\/\/arquitecturamediterrania.com\/#website","url":"https:\/\/arquitecturamediterrania.com\/","name":"Arquitectura Mediterr\u00e0nia","description":"Nous construisons des espaces m\u00e9diterran\u00e9ens, sains et durables","publisher":{"@id":"https:\/\/arquitecturamediterrania.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/arquitecturamediterrania.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/arquitecturamediterrania.com\/#organization","name":"Arquitectura Mediterr\u00e0nia","url":"https:\/\/arquitecturamediterrania.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/arquitecturamediterrania.com\/#\/schema\/logo\/image\/","url":"https:\/\/arquitecturamediterrania.com\/wp-content\/uploads\/2025\/01\/logotip-am.svg","contentUrl":"https:\/\/arquitecturamediterrania.com\/wp-content\/uploads\/2025\/01\/logotip-am.svg","width":499,"height":215,"caption":"Arquitectura Mediterr\u00e0nia"},"image":{"@id":"https:\/\/arquitecturamediterrania.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/arquitecturamediterrania.com\/fr\/wp-json\/wp\/v2\/pages\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/arquitecturamediterrania.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/arquitecturamediterrania.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/arquitecturamediterrania.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/arquitecturamediterrania.com\/fr\/wp-json\/wp\/v2\/comments?post=2542"}],"version-history":[{"count":3,"href":"https:\/\/arquitecturamediterrania.com\/fr\/wp-json\/wp\/v2\/pages\/2542\/revisions"}],"predecessor-version":[{"id":3011,"href":"https:\/\/arquitecturamediterrania.com\/fr\/wp-json\/wp\/v2\/pages\/2542\/revisions\/3011"}],"wp:attachment":[{"href":"https:\/\/arquitecturamediterrania.com\/fr\/wp-json\/wp\/v2\/media?parent=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}